{"id":16,"count":11,"description":"Mejora tu experiencia radiof\u00f3nica con nuestra amplia gama de antenas, soportes, micr\u00f3fonos, cables y accesorios esenciales de alta calidad para un rendimiento \u00f3ptimo de las comunicaciones.","link":"https:\/\/bestcbradio.com\/es\/accesorios\/","name":"ACCESORIOS","slug":"accesorios","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/bestcbradio.com\/es\/wp-json\/wp\/v2\/product_cat\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bestcbradio.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/bestcbradio.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/bestcbradio.com\/es\/wp-json\/wp\/v2\/product?product_cat=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}